{"id":94,"date":"2020-03-10T14:20:06","date_gmt":"2020-03-10T13:20:06","guid":{"rendered":"https:\/\/garnelen-direkt.de\/wiki\/?p=94"},"modified":"2024-11-13T12:16:46","modified_gmt":"2024-11-13T11:16:46","slug":"leitwert-was-ist-das-eigentlich","status":"publish","type":"post","link":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/","title":{"rendered":"Leitwert im Aquarium"},"content":{"rendered":"\n<p>Der Leitwert im Aquarium sagt aus, wie gut elektrische Energie durch das Aquarienwasser flie\u00dfen kann. Destilliertes Wasser ist nicht leitf\u00e4hig, je mehr Salze darin gel\u00f6st sind, um so besser kann ein Strom darin flie\u00dfen.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><strong> 1\u00b0 Deutsche Gesamth\u00e4rte machen etwa 30 &#8211; 35 \u00b5\/S (Microsiemens) aus. <\/strong><\/p>\n\n\n\n<p>Angenommen das Ausgangswasser wei\u00dft 10\u00b0 DGh auf, <br>dann sollte der Leitwert etwa bei 300 &#8211; 350 \u00b5\/S liegen. <\/p>\n\n\n\n<p>Der Leitwert l\u00e4sst sich schnell und einfach mit einem <a href=\"https:\/\/garnelen-direkt.de\/Technik\/nuetzliches\/leitwertmessgeraet-mikrosiemens-anzeige-hm-ap-2.html\">Leitwertmessger\u00e4t<\/a> messen. <\/p>\n\n\n\n<p>Leider funktioniert dieses theoretische Beispiel in der Praxis nicht! Denn Nitrat, Phosphat, Spurenelemente, also alle l\u00f6slichen Salze in unserem Wasser erh\u00f6hen den Leitwert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Also was sagt uns dann der Leitwert im Aquarium \u00fcberhaupt?<\/strong><\/h2>\n\n\n\n<p>Wenn ich also wei\u00df, dass mein Ausgangswasser beispielsweise 600 \u00b5\/S hat und nach einer Woche der Leitwert sich im Aquarium stark erh\u00f6ht hat, dann ist irgendetwas im Argen.<\/p>\n\n\n\n<p>Aber warum wird der <a href=\"https:\/\/www.fischlexikon.eu\/aquaristik\/aquarien-chemie\/leitwert.php#:~:text=Im%20Aquarium%20stellen%20Leitwerte%20von,mit%20einem%20Leitwertmessger%C3%A4t%20ermittelt%20werden.\">Leitwert<\/a> immer so h\u00e4ufig genannt und wieso ist er so wichtig?<\/p>\n\n\n\n<p>Ganz einfach, gerade in der Zierfischzucht und Garnelenzucht, wird meist sehr weiches Wasser ben\u00f6tigt, damit die Tiere sich wohlf\u00fchlen, ablaichen und der Laich nicht verpilzt.<br>Dazu benutzt man <a href=\"https:\/\/garnelen-direkt.de\/Technik\/osmoseanlagen\/\">Umkehr-Osmose-Wasser<\/a>, wobei man meist nur Osmosewasser sagt, dieses Wasser ist fast reines Wasser (zu 98 %) und muss aufgesalzen werden.<br>Reines Osmosewasser sollte man auf keinen Fall so in das Aquarium geben, da dies fatale Folgen f\u00fcr die Lebewesen in einem Aquarium h\u00e4tte.<br>Zum Aufsalzen gibt es spezielle <a href=\"https:\/\/garnelen-direkt.de\/Pflege\/Pflanzenduenger\/prism-shrimp-minerals-gh-kh-neo-original.html\">Salze<\/a>.<\/p>\n\n\n\n<p>Und nun kommen wir zum Leitwert: durch die Salze erh\u00f6hen wir den Leitwert in unserem Osmose-Wasser. Dazu f\u00e4ngt man das Permeat (frisches, unbehandeltes Wasser aus der <a href=\"https:\/\/garnelen-direkt.de\/Technik\/osmoseanlagen\/\">Umkehr-Osmose-Anlage<\/a>)<br>in einem Beh\u00e4lter auf, gibt das <a href=\"https:\/\/garnelen-direkt.de\/Pflege\/Pflanzenduenger\/prism-shrimp-minerals-gh-kh-neo-original.html\">Aufh\u00e4rtesalz<\/a> dazu, r\u00fchrt kurz um und misst den Leitwert mit dem <a href=\"https:\/\/garnelen-direkt.de\/Technik\/nuetzliches\/leitwertmessgeraet-mikrosiemens-anzeige-hm-ap-2.html\">Leitwert-Messger\u00e4t<\/a>.<\/p>\n\n\n\n<p><strong>Bei <a href=\"https:\/\/garnelen-direkt.de\/Tiere\/Garnelen\/\">Garnelen<\/a> empfiehlt es sich einen Leitwert von etwa 250 \u00b5\/S zu erreichen.<\/strong><\/p>\n\n\n\n<p>Die Salze sind optimal auf die Bed\u00fcrfnisse der <a href=\"https:\/\/garnelen-direkt.de\/Tiere\/Garnelen\/\">Garnelen<\/a> abgestimmt, daher haben wir f\u00fcr verschiedene Gattungen von <a href=\"https:\/\/garnelen-direkt.de\/Tiere\/Garnelen\/\">Garnelen<\/a> auch verschiedene <a href=\"https:\/\/garnelen-direkt.de\/Pflege\/Pflanzenduenger\/prism-shrimp-minerals-gh-kh-neo-original.html\">Salze<\/a>.<br>Mit den <a href=\"https:\/\/garnelen-direkt.de\/Pflege\/Pflanzenduenger\/prism-shrimp-minerals-gh-kh-neo-original.html\">Salzen<\/a> geben wir auch Spurenelemente und Mineralien in das Wechselwasser und erzielen damit ein artgerechtes Wasser f\u00fcr die Aquarienbewohner.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Leitwert im Aquarium sagt aus, wie gut elektrische Energie durch das Aquarienwasser flie\u00dfen kann. Destilliertes Wasser ist nicht leitf\u00e4hig, je mehr Salze darin gel\u00f6st sind, um so besser kann ein Strom darin flie\u00dfen. 1\u00b0 Deutsche Gesamth\u00e4rte machen etwa 30 &#8211; 35 \u00b5\/S (Microsiemens) aus. Angenommen das Ausgangswasser wei\u00dft 10\u00b0 DGh auf, dann sollte der &hellip; <a href=\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5,8,6,10,7,9],"class_list":["post-94","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-aquarium","tag-garnelen","tag-leitwert","tag-mineralien","tag-osmose","tag-zierfische"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Leitwert im Aquarium - Garnelen-Direkt Wiki<\/title>\n<meta name=\"description\" content=\"Lerne, wie der Leitwert im Aquarium das Wohlbefinden von Fischen und Garnelen beeinflusst und mit speziellen Salzen optimiert werden kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leitwert im Aquarium - Garnelen-Direkt Wiki\" \/>\n<meta property=\"og:description\" content=\"Lerne, wie der Leitwert im Aquarium das Wohlbefinden von Fischen und Garnelen beeinflusst und mit speziellen Salzen optimiert werden kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\" \/>\n<meta property=\"og:site_name\" content=\"Garnelen-Direkt Wiki\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/garnelendirekt\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T13:20:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T11:16:46+00:00\" \/>\n<meta name=\"author\" content=\"Frank Junior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frank Junior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\"},\"author\":{\"name\":\"Frank Junior\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/person\/399a3b09319edcdcdb999a7f05d218f1\"},\"headline\":\"Leitwert im Aquarium\",\"datePublished\":\"2020-03-10T13:20:06+00:00\",\"dateModified\":\"2024-11-13T11:16:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#organization\"},\"keywords\":[\"Aquarium\",\"Garnelen\",\"Leitwert\",\"Mineralien\",\"Osmose\",\"Zierfische\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\",\"url\":\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\",\"name\":\"Leitwert im Aquarium - Garnelen-Direkt Wiki\",\"isPartOf\":{\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#website\"},\"datePublished\":\"2020-03-10T13:20:06+00:00\",\"dateModified\":\"2024-11-13T11:16:46+00:00\",\"description\":\"Lerne, wie der Leitwert im Aquarium das Wohlbefinden von Fischen und Garnelen beeinflusst und mit speziellen Salzen optimiert werden kann.\",\"breadcrumb\":{\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/garnelen-direkt.de\/wiki\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leitwert im Aquarium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#website\",\"url\":\"https:\/\/garnelen-direkt.de\/wiki\/\",\"name\":\"Garnelen-Direkt Wiki\",\"description\":\"Wissenswertes von den Profis\",\"publisher\":{\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/garnelen-direkt.de\/wiki\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#organization\",\"name\":\"garnelen-direkt.de\",\"url\":\"https:\/\/garnelen-direkt.de\/wiki\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/garnelen-direkt.de\/wiki\/wp-content\/uploads\/2019\/08\/42533389_337472143732913_5748895862650568704_n.png\",\"contentUrl\":\"https:\/\/garnelen-direkt.de\/wiki\/wp-content\/uploads\/2019\/08\/42533389_337472143732913_5748895862650568704_n.png\",\"width\":2048,\"height\":299,\"caption\":\"garnelen-direkt.de\"},\"image\":{\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/garnelendirekt\/\",\"https:\/\/www.instagram.com\/garnelendirektofficial\/\",\"https:\/\/www.youtube.com\/channel\/UCMB4WNCpFSEC_oRCDZED8Gg\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/person\/399a3b09319edcdcdb999a7f05d218f1\",\"name\":\"Frank Junior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/23972717cb5a932e0a98e76d49ac5bfc5d919195fc396beae4dd0561e5670d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/23972717cb5a932e0a98e76d49ac5bfc5d919195fc396beae4dd0561e5670d94?s=96&d=mm&r=g\",\"caption\":\"Frank Junior\"},\"sameAs\":[\"http:\/\/www.garnelen-direkt.de\"],\"url\":\"https:\/\/garnelen-direkt.de\/wiki\/author\/frank\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leitwert im Aquarium - Garnelen-Direkt Wiki","description":"Lerne, wie der Leitwert im Aquarium das Wohlbefinden von Fischen und Garnelen beeinflusst und mit speziellen Salzen optimiert werden kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/","og_locale":"de_DE","og_type":"article","og_title":"Leitwert im Aquarium - Garnelen-Direkt Wiki","og_description":"Lerne, wie der Leitwert im Aquarium das Wohlbefinden von Fischen und Garnelen beeinflusst und mit speziellen Salzen optimiert werden kann.","og_url":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/","og_site_name":"Garnelen-Direkt Wiki","article_publisher":"https:\/\/www.facebook.com\/garnelendirekt\/","article_published_time":"2020-03-10T13:20:06+00:00","article_modified_time":"2024-11-13T11:16:46+00:00","author":"Frank Junior","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Frank Junior","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#article","isPartOf":{"@id":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/"},"author":{"name":"Frank Junior","@id":"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/person\/399a3b09319edcdcdb999a7f05d218f1"},"headline":"Leitwert im Aquarium","datePublished":"2020-03-10T13:20:06+00:00","dateModified":"2024-11-13T11:16:46+00:00","mainEntityOfPage":{"@id":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/garnelen-direkt.de\/wiki\/#organization"},"keywords":["Aquarium","Garnelen","Leitwert","Mineralien","Osmose","Zierfische"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/","url":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/","name":"Leitwert im Aquarium - Garnelen-Direkt Wiki","isPartOf":{"@id":"https:\/\/garnelen-direkt.de\/wiki\/#website"},"datePublished":"2020-03-10T13:20:06+00:00","dateModified":"2024-11-13T11:16:46+00:00","description":"Lerne, wie der Leitwert im Aquarium das Wohlbefinden von Fischen und Garnelen beeinflusst und mit speziellen Salzen optimiert werden kann.","breadcrumb":{"@id":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/garnelen-direkt.de\/wiki\/2020\/03\/10\/leitwert-was-ist-das-eigentlich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/garnelen-direkt.de\/wiki\/"},{"@type":"ListItem","position":2,"name":"Leitwert im Aquarium"}]},{"@type":"WebSite","@id":"https:\/\/garnelen-direkt.de\/wiki\/#website","url":"https:\/\/garnelen-direkt.de\/wiki\/","name":"Garnelen-Direkt Wiki","description":"Wissenswertes von den Profis","publisher":{"@id":"https:\/\/garnelen-direkt.de\/wiki\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/garnelen-direkt.de\/wiki\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/garnelen-direkt.de\/wiki\/#organization","name":"garnelen-direkt.de","url":"https:\/\/garnelen-direkt.de\/wiki\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/logo\/image\/","url":"https:\/\/garnelen-direkt.de\/wiki\/wp-content\/uploads\/2019\/08\/42533389_337472143732913_5748895862650568704_n.png","contentUrl":"https:\/\/garnelen-direkt.de\/wiki\/wp-content\/uploads\/2019\/08\/42533389_337472143732913_5748895862650568704_n.png","width":2048,"height":299,"caption":"garnelen-direkt.de"},"image":{"@id":"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/garnelendirekt\/","https:\/\/www.instagram.com\/garnelendirektofficial\/","https:\/\/www.youtube.com\/channel\/UCMB4WNCpFSEC_oRCDZED8Gg"]},{"@type":"Person","@id":"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/person\/399a3b09319edcdcdb999a7f05d218f1","name":"Frank Junior","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/garnelen-direkt.de\/wiki\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/23972717cb5a932e0a98e76d49ac5bfc5d919195fc396beae4dd0561e5670d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23972717cb5a932e0a98e76d49ac5bfc5d919195fc396beae4dd0561e5670d94?s=96&d=mm&r=g","caption":"Frank Junior"},"sameAs":["http:\/\/www.garnelen-direkt.de"],"url":"https:\/\/garnelen-direkt.de\/wiki\/author\/frank\/"}]}},"_links":{"self":[{"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/posts\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":5,"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/posts\/94\/revisions"}],"predecessor-version":[{"id":131,"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/posts\/94\/revisions\/131"}],"wp:attachment":[{"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/media?parent=94"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/categories?post=94"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/garnelen-direkt.de\/wiki\/wp-json\/wp\/v2\/tags?post=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}